{"id":1238,"date":"2018-10-04T17:12:59","date_gmt":"2018-10-04T17:12:59","guid":{"rendered":"https:\/\/www.bluerepublic.com\/contact-us\/"},"modified":"2020-01-28T15:38:03","modified_gmt":"2020-01-28T15:38:03","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.bluerepublic.com\/fr\/contact-us\/","title":{"rendered":"Nous contacter"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1238\" class=\"elementor elementor-1238 elementor-82\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d6eaf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d6eaf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed7fb40\" data-id=\"ed7fb40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32f130d elementor-widget elementor-widget-text-editor\" data-id=\"32f130d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<h3>Remplissez le formulaire et nous vous contacterons d\u00e8s que possible.<\/h3>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element titulares\">\n<div class=\"wpb_wrapper\">\n<p class=\"text-intro\">Remplissez le formulaire et nous vous contacterons d\u00e8s que possible.<\/p>\n\n<\/div>\n<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a98a95 elementor-widget elementor-widget-shortcode\" data-id=\"2a98a95\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f1748-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/1238#wpcf7-f1748-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1748\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1748-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Your Name (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your Email (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Subject (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your Message (required)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span> <\/label>\n<div style=\"margin-bottom:9px;margin-top: -14px;\"><span class=\"wpcf7-form-control-wrap acceptance-314\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-314\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>I have read and agree Blue Republic's <a style=\"margin-top:0px;\" class=\"link\" target=\"_blank\" href=\"https:\/\/www.bluerepublic.com\/privacy-policy\/\">Privacy Policy<\/a><\/div>\n<p><!-- Mailchimp for WordPress v4.8.1 - https:\/\/www.mc4wp.com\/ --><input type=\"hidden\" name=\"_mc4wp_subscribe_contact-form-7\" value=\"0\" \/><span class=\" mc4wp-checkbox mc4wp-checkbox-contact-form-7\" ><label><input type=\"checkbox\" name=\"_mc4wp_subscribe_contact-form-7\" value=\"1\"  \/><span>Sign me up for the newsletter!<\/span><\/label><\/span><!-- \/ Mailchimp for WordPress --><br \/>\n<div class=\"anr_captcha_field\"><div id=\"anr_captcha_field_1\" class=\"anr_captcha_field_div\"><input type=\"hidden\" name=\"g-recaptcha-response\" value=\"\" \/><\/div><\/div><span class=\"wpcf7-form-control-wrap g-recaptcha-response\"><\/span><br \/>\n<input type=\"submit\" value=\"Send Message\" class=\"wpcf7-form-control wpcf7-submit acf-button button-primary\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4fd830 elementor-hidden-phone\" data-id=\"e4fd830\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b091b8 elementor-widget elementor-widget-image\" data-id=\"1b091b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"576\" height=\"1024\" src=\"https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3-576x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3.jpg 576w, https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3-169x300.jpg 169w, https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3-768x1365.jpg 768w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Remplissez le formulaire et nous vous contacterons d\u00e8s que possible. Remplissez le formulaire et nous vous contacterons d\u00e8s que possible.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nous contacter - BlueRepublic\" \/>\n<meta property=\"og:description\" content=\"Remplissez le formulaire et nous vous contacterons d\u00e8s que possible. Remplissez le formulaire et nous vous contacterons d\u00e8s que possible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"BlueRepublic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MrsBlueRepublic\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-28T15:38:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3-576x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bluerepublic.com\/#organization\",\"name\":\"bluerepublic.com\",\"url\":\"https:\/\/www.bluerepublic.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/MrsBlueRepublic\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bluerepublic.com\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/11\/logoComplete.png\",\"width\":600,\"height\":277,\"caption\":\"bluerepublic.com\"},\"image\":{\"@id\":\"https:\/\/www.bluerepublic.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bluerepublic.com\/#website\",\"url\":\"https:\/\/www.bluerepublic.com\/\",\"name\":\"BlueRepublic\",\"description\":\"Linked by the Ocean\",\"publisher\":{\"@id\":\"https:\/\/www.bluerepublic.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.bluerepublic.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.bluerepublic.com\/wp-content\/uploads\/2018\/12\/shutterstock_130948589-3.jpg\",\"width\":576,\"height\":1024},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/#webpage\",\"url\":\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/\",\"name\":\"Nous contacter - BlueRepublic\",\"isPartOf\":{\"@id\":\"https:\/\/www.bluerepublic.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/#primaryimage\"},\"datePublished\":\"2018-10-04T17:12:59+00:00\",\"dateModified\":\"2020-01-28T15:38:03+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bluerepublic.com\/fr\/contact-us\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/pages\/1238"}],"collection":[{"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/comments?post=1238"}],"version-history":[{"count":5,"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/pages\/1238\/revisions"}],"predecessor-version":[{"id":1777,"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/pages\/1238\/revisions\/1777"}],"wp:attachment":[{"href":"https:\/\/www.bluerepublic.com\/fr\/wp-json\/wp\/v2\/media?parent=1238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}